{"id":3575,"date":"2025-12-23T19:16:36","date_gmt":"2025-12-23T18:16:36","guid":{"rendered":"https:\/\/www.relyonelectrical.be\/careers\/"},"modified":"2026-05-22T16:19:39","modified_gmt":"2026-05-22T14:19:39","slug":"careers","status":"publish","type":"page","link":"https:\/\/www.relyonelectrical.be\/en\/careers\/","title":{"rendered":"Careers"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row full_width=&#8221;stretch_row&#8221; remove_bottom_col_margin=&#8221;true&#8221; columns_right=&#8221;yes&#8221; offset_overlay_header=&#8221;yes&#8221; css=&#8221;.vc_custom_1765193168712{background-position: 0 0 !important;background-repeat: no-repeat !important;}&#8221;][vc_column width=&#8221;2\/5&#8243;]<figure class=\"vcex-image vcex-module intro-image turcuoise\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"2560\" height=\"1707\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled.jpg\" class=\"vcex-image-img wpex-align-middle wpex-aspect-1-1 wpex-object-cover\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-768x512.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-1536x1024.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/figure>[\/vc_column][vc_column width=&#8221;3\/5&#8243;]<style>.vcex-heading.vcex_6a982ab225148 .vcex-heading-badge{color:var(--wpex-palette-27-color);}.vcex-heading.vcex_6a982ab225148{width:500px;font-size:var(--wpex-text-3xl);}@media (max-width:479px){.vcex-heading.vcex_6a982ab225148{font-size:var(--wpex-text-5xl);}}<\/style><h1 class=\"vcex-heading vcex-heading-plain vcex-heading-w-badge vcex-module wpex-heading wpex-text-2xl wpex-h1 wpex-max-w-100 wpex-mr-auto vcex_6a982ab225148\"><span class=\"vcex-heading-inner wpex-inline-block\">Do you enjoy working independently while still being able to count on a warm and friendly team? <span class=\"vcex-heading-badge wpex-badge\">Come work at RelyOn Electrical Services<\/span><\/span><\/h1><div class=\"vcex-spacing wpex-w-100 wpex-clear\"><\/div>[vc_column_text css=&#8221;&#8221; font_size=&#8221;d:lg|pp:xl&#8221; line_height=&#8221;1.5em&#8221;]<strong>Can you see yourself fitting into a group of passionate colleagues?<\/strong><\/p>\n<p><span style=\"font-weight: 400;\">At RelyOn Electrical Services, you are given the trust and mandate to <strong>organize your own projects and client work<\/strong>, but you can always turn to your colleagues\u2014including technicians, operational, administrative, and management profiles\u2014with any questions, especially when you have just started.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">We are happy to show you how we approach our work; you will be given time to get to know our operations and clients, and you can shadow one of your colleagues to master everything before taking full charge! Furthermore, you are encouraged\u2014as you bring a fresh perspective\u2014to <strong>help refine and build<\/strong> the efficient operations of RelyOn Electrical Services.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">We consistently strive for <strong>team goals<\/strong>, so we do not engage in internal competition. We <strong>help each other<\/strong> and RelyOn Electrical Services reach greater heights and can always rely on one another.<strong> We celebrate successes<\/strong>. And other occasions too, as there is always a reason for cake or pastries.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Enough about us. We would now like to get to know you. View our vacancies and apply today!<\/span>[\/vc_column_text][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row&#8221; wpex_bg_overlay=&#8221;color&#8221; wpex_bg_overlay_color=&#8221;palette-26&#8243; wpex_bg_overlay_opacity=&#8221;100&#8243;][vc_column]<div class=\"vcex-spacing wpex-w-100 wpex-clear show-at-mm-breakpoint\"><\/div><style>.vcex-heading.vcex_6a982ab225e47{width:500px;color:var(--wpex-palette-18-color);font-size:var(--wpex-text-3xl);}<\/style><h2 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h2 wpex-mb-20 wpex-text-center wpex-max-w-100 wpex-mx-auto vcex_6a982ab225e47\"><span class=\"vcex-heading-inner wpex-inline-block\">Current vacancies<\/span><\/h2><div class=\"vcex-spacing wpex-w-100 wpex-clear\"><\/div><div class=\"wpex-post-cards wpex-post-cards-template_1730 wpex-relative\"><div class=\"wpex-post-cards-inner\"><div class=\"wpex-post-cards-loop wpex-post-cards-grid wpex-row wpex-clr gap-50\"><div class=\"wpex-post-cards-entry col col-1 span_1_of_3 post-3990 type-jobs\"><div class=\"wpex-card wpex-card-template_1730 vacature-card\"><div class=\"wpex-card-inner\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style>.vcex-image.vcex_6a982ab228271 .vcex-image-img{border-radius:var(--wpex-rounded-xl);}<\/style><figure class=\"vcex-image vcex-module vcex_6a982ab228271\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/electrical-engineer\/\"><img width=\"1500\" height=\"1000\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2022\/10\/vacature-electrical-engineer.jpg\" class=\"vcex-image-img wpex-align-middle wpex-aspect-4-3 wpex-object-cover\" alt=\"Vacature Electrical Engineer\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2022\/10\/vacature-electrical-engineer.jpg 1500w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2022\/10\/vacature-electrical-engineer-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2022\/10\/vacature-electrical-engineer-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2022\/10\/vacature-electrical-engineer-768x512.jpg 768w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/a><\/div><\/figure><style>.vcex-heading.vcex_6a982ab228ac9{color:var(--wpex-palette-18-color);font-weight:600;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h3 wpex-mt-20 wpex-mb-20 vcex_6a982ab228ac9\"><span class=\"vcex-heading-inner wpex-inline-block\">Electrical Engineer<\/span><\/h3><div class=\"vcex-post-excerpt vcex-module wpex-text-pretty wpex-last-mb-0 wpex-line-clamp-4\"><p>We are quite passionate about everything related to electricity.<br \/>\nAs an independent partner, we help our clients keep their workplace safe.<br \/>\nFor instance, we are engaged for Risk Analyses, Energy Advice, and Electrical Engineering.<\/p>\n<\/div><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/electrical-engineer\/\" class=\"vcex-button theme-button white small inline\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">read more<\/span><\/a> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpex-post-cards-entry col col-2 span_1_of_3 post-3977 type-jobs\"><div class=\"wpex-card wpex-card-template_1730 vacature-card\"><div class=\"wpex-card-inner\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style>.vcex-image.vcex_6a982ab229f61 .vcex-image-img{border-radius:var(--wpex-rounded-xl);}<\/style><figure class=\"vcex-image vcex-module vcex_6a982ab229f61\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/business-development-manager\/\"><img width=\"2560\" height=\"1707\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled.jpg\" class=\"vcex-image-img wpex-align-middle wpex-aspect-4-3 wpex-object-cover\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-768x512.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-1536x1024.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/2023-09-04Bureau9000-383-scaled-2048x1366.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><style>.vcex-heading.vcex_6a982ab22a5e2{color:var(--wpex-palette-18-color);font-weight:600;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h3 wpex-mt-20 wpex-mb-20 vcex_6a982ab22a5e2\"><span class=\"vcex-heading-inner wpex-inline-block\">Business Development Manager<\/span><\/h3><div class=\"vcex-post-excerpt vcex-module wpex-text-pretty wpex-last-mb-0 wpex-line-clamp-4\"><p>You will become the primary point of contact for technical inquiries from (potential) clients.<br \/>\nYou will analyze their requirements, identify technical solutions, and translate these into clear and persuasive proposals.<\/p>\n<\/div><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/business-development-manager\/\" class=\"vcex-button theme-button white small inline\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">read more<\/span><\/a> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpex-post-cards-entry col col-3 span_1_of_3 post-3974 type-jobs\"><div class=\"wpex-card wpex-card-template_1730 vacature-card\"><div class=\"wpex-card-inner\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style>.vcex-image.vcex_6a982ab22b48d .vcex-image-img{border-radius:var(--wpex-rounded-xl);}<\/style><figure class=\"vcex-image vcex-module vcex_6a982ab22b48d\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/instructor-electricity-trainer-ba4-ba5-hv-arei\/\"><img width=\"2560\" height=\"1709\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_1192486477-scaled.jpg\" class=\"vcex-image-img wpex-align-middle wpex-aspect-4-3 wpex-object-cover\" alt=\"BA5 Refresher Training\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_1192486477-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_1192486477-scaled-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_1192486477-scaled-1024x684.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_1192486477-scaled-768x513.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_1192486477-scaled-1536x1025.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_1192486477-scaled-2048x1367.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><style>.vcex-heading.vcex_6a982ab22bdf1{color:var(--wpex-palette-18-color);font-weight:600;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h3 wpex-mt-20 wpex-mb-20 vcex_6a982ab22bdf1\"><span class=\"vcex-heading-inner wpex-inline-block\">Instructor \/ Electricity Trainer (BA4\/BA5\/HV\/AREI)<\/span><\/h3><div class=\"vcex-post-excerpt vcex-module wpex-text-pretty wpex-last-mb-0 wpex-line-clamp-4\"><p>Bureau 9000 specializes, among other things, in training professionals in electrical safety. These courses focus on familiarizing employees with the risks associated with electrical installations. <\/p>\n<\/div><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/instructor-electricity-trainer-ba4-ba5-hv-arei\/\" class=\"vcex-button theme-button white small inline\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">read more<\/span><\/a> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"wpex-post-cards-entry col col-1 span_1_of_3 post-4001 type-jobs\"><div class=\"wpex-card wpex-card-template_1730 vacature-card\"><div class=\"wpex-card-inner\"><div class=\"vc_row wpb_row vc_row-fluid wpex-relative wpex-vc_row-col-mb-0\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><style>.vcex-image.vcex_6a982ab22cc4f .vcex-image-img{border-radius:var(--wpex-rounded-xl);}<\/style><figure class=\"vcex-image vcex-module vcex_6a982ab22cc4f\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/spontaneous-application-internship-inquiry\/\"><img width=\"2560\" height=\"1696\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_118198651-scaled.jpg\" class=\"vcex-image-img wpex-align-middle wpex-aspect-4-3 wpex-object-cover\" alt=\"\" loading=\"lazy\" decoding=\"async\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_118198651-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_118198651-scaled-300x199.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_118198651-scaled-1024x678.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_118198651-scaled-768x509.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_118198651-scaled-1536x1018.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2025\/12\/shutterstock_118198651-scaled-2048x1357.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><style>.vcex-heading.vcex_6a982ab22d357{color:var(--wpex-palette-18-color);font-weight:600;}<\/style><h3 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h3 wpex-mt-20 wpex-mb-20 vcex_6a982ab22d357\"><span class=\"vcex-heading-inner wpex-inline-block\">Spontaneous application \/ Internship inquiry<\/span><\/h3><div class=\"vcex-post-excerpt vcex-module wpex-text-pretty wpex-last-mb-0 wpex-line-clamp-4\"><p>Bureau 9000 is a rapidly growing company! If you do not immediately find a suitable position among our current vacancies, but you feel a connection with who we are, please leave your CV and cover letter here.  <\/p>\n<\/div><div class=\"vcex-spacing wpex-w-100 wpex-clear\" style=\"height:20px;\"><\/div><a href=\"https:\/\/www.relyonelectrical.be\/en\/jobs\/spontaneous-application-internship-inquiry\/\" class=\"vcex-button theme-button white small inline\"><span class=\"vcex-button-inner theme-button-inner wpex-flex wpex-flex-wrap wpex-items-center wpex-justify-center\">read more<\/span><\/a> <\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vcex-spacing wpex-w-100 wpex-clear show-at-mm-breakpoint\"><\/div>[\/vc_column][\/vc_row][vc_row][vc_column]<style>.vcex-heading.vcex_6a982ab22e7c8{width:500px;}<\/style><h2 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h2 wpex-max-w-100 wpex-mr-auto vcex_6a982ab22e7c8\"><span class=\"vcex-heading-inner wpex-inline-block\">A glimpse of the atmosphere<\/span><\/h2><div class=\"vcex-spacing wpex-w-100 wpex-clear\"><\/div><div class=\"vcex-image-grid-wrap\"><div class=\"vcex-module vcex-image-grid grid-style-masonry wpex-row wpex-clr vcex-isotope-grid no-transition wpex-overflow-hidden wpex-lightbox-group\" data-transition-duration=\"0.0\"><div class=\"id-3688 vcex-image-grid-entry vcex-grid-item vcex-isotope-entry wpex-text-center span_1_of_4 span_1_of_3_tp span_1_of_3_pl span_1_of_2_pp col col-1\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-scaled.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"2560\" height=\"1707\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-scaled.jpg\" class=\"wpex-align-middle skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-768x512.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-1536x1024.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-76-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-3869 vcex-image-grid-entry vcex-grid-item vcex-isotope-entry wpex-text-center span_1_of_4 span_1_of_3_tp span_1_of_3_pl span_1_of_2_pp col col-2\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-scaled.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"2560\" height=\"1707\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-scaled.jpg\" class=\"wpex-align-middle skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-768x512.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-1536x1024.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-32-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-3576 vcex-image-grid-entry vcex-grid-item vcex-isotope-entry wpex-text-center span_1_of_4 span_1_of_3_tp span_1_of_3_pl span_1_of_2_pp col col-3\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-scaled.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"2560\" height=\"1707\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-scaled.jpg\" class=\"wpex-align-middle skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-768x512.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-1536x1024.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-11-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-3577 vcex-image-grid-entry vcex-grid-item vcex-isotope-entry wpex-text-center span_1_of_4 span_1_of_3_tp span_1_of_3_pl span_1_of_2_pp col col-4\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-scaled.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"2560\" height=\"1707\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-scaled.jpg\" class=\"wpex-align-middle skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-768x512.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-1536x1024.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-52-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><\/div><div class=\"id-3579 vcex-image-grid-entry vcex-grid-item vcex-isotope-entry wpex-text-center span_1_of_4 span_1_of_3_tp span_1_of_3_pl span_1_of_2_pp col col-1\"><figure class=\"vcex-image-grid-entry-figure wpex-last-mb-0 wpex-clr\"><div class=\"vcex-image-grid-entry-img entry-media wpex-relative wpex-mb-20\"><a href=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-scaled.jpg\" class=\"vcex-image-grid-entry-link wpex-lightbox-group-item\" ><img width=\"2560\" height=\"1707\" src=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-scaled.jpg\" class=\"wpex-align-middle skip-lazy\" alt=\"\" data-no-lazy=\"1\" srcset=\"https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-scaled.jpg 2560w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-300x200.jpg 300w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-1024x683.jpg 1024w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-768x512.jpg 768w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-1536x1024.jpg 1536w, https:\/\/www.relyonelectrical.be\/wp-content\/uploads\/2026\/03\/2026-01-23RelyOn-133-2048x1365.jpg 2048w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/><\/a><\/div><\/figure><\/div><\/div><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":5,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3575","page","type-page","status-publish","hentry","entry","no-media"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/pages\/3575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/comments?post=3575"}],"version-history":[{"count":8,"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/pages\/3575\/revisions"}],"predecessor-version":[{"id":6625,"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/pages\/3575\/revisions\/6625"}],"wp:attachment":[{"href":"https:\/\/www.relyonelectrical.be\/en\/wp-json\/wp\/v2\/media?parent=3575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}